{"id":15775,"date":"2024-06-13T08:54:20","date_gmt":"2024-06-13T08:54:20","guid":{"rendered":"https:\/\/rjydisplay.com\/project\/project002\/"},"modified":"2026-06-02T10:05:50","modified_gmt":"2026-06-02T10:05:50","slug":"solutions-for-smart-wearables","status":"publish","type":"industry","link":"https:\/\/rjydisplay.com\/fr\/industry\/solutions-for-smart-wearables\/","title":{"rendered":"Appareils portables intelligents"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"15775\" class=\"elementor elementor-15775\" data-elementor-post-type=\"industry\">\n\t\t\t\t<div class=\"elementor-element elementor-element-495c007 e-con-full e-flex e-con e-parent\" data-id=\"495c007\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-76203ef e-con-full e-flex e-con e-child\" data-id=\"76203ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af86d70 e-con-full e-flex e-con e-child\" data-id=\"af86d70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b45e86f elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b45e86f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Appareils portables intelligents<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f5bd4f e-flex e-con-boxed e-con e-parent\" data-id=\"1f5bd4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6960dd7 e-con-full e-flex e-con e-child\" data-id=\"6960dd7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff282f9 elementor-widget elementor-widget-heading\" data-id=\"ff282f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pionnier de la vie connect\u00e9e de nouvelle g\u00e9n\u00e9ration avec les solutions portables intelligentes RJY<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55ce1e8 elementor-widget elementor-widget-text-editor\" data-id=\"55ce1e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDans l'\u00e9volution rapide de la sant\u00e9 mobile et des technologies grand public, une efficacit\u00e9 \u00e9nerg\u00e9tique exceptionnelle et une IHM compacte d\u00e9finissent les appareils portables de premier ordre. RJY Display propose des modules d'affichage ultra-minces et des plates-formes informatiques hautement int\u00e9gr\u00e9es, optimis\u00e9es pour les montres connect\u00e9es robustes, les bracelets de fitness grand public et les lunettes AR industrielles l\u00e9g\u00e8res.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fb3286 elementor-align-center elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"2fb3286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nous contacter<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa8a29d e-con-full e-flex e-con e-parent\" data-id=\"fa8a29d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cb9862 elementor-widget elementor-widget-heading\" data-id=\"0cb9862\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sc\u00e9narios d'application<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-396e4db elementor-widget elementor-widget-text-editor\" data-id=\"396e4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Alimentation des montres de sport et des \u00e9quipements de suivi ext\u00e9rieur robustes. Nos \u00e9crans \u00e0 haute r\u00e9sistance et nos configurations mat\u00e9rielles \u00e0 faible consommation g\u00e8rent la t\u00e9l\u00e9m\u00e9trie GPS multi-satellites et la surveillance continue de la fr\u00e9quence cardiaque dans des conditions de plein soleil ext\u00e9rieur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ba2bbb e-grid e-con-full e-con e-child\" data-id=\"4ba2bbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83f1950 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"83f1950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/elementor\/thumbs\/fall-detector-scaled-1-rpb9rvrqizem0b311968f7xye0h8cyow11lfic77pc.jpg\" title=\"D\u00e9tecteur de chute \u00c9chelle 1\" alt=\"Fall Detector Scaled 1\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Soins aux personnes \u00e2g\u00e9es<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef1d6a7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ef1d6a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1-.jpg\" class=\"attachment-full size-full wp-image-45597\" alt=\"\" title=\"\" srcset=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1-.jpg 2000w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1--300x200.jpg 300w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1--1024x683.jpg 1024w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1--768x512.jpg 768w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1--1536x1025.jpg 1536w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2024\/06\/Amazon-One-Enterprise_AOE_Office-Entry_hand-hover_alt-person-4-1--18x12.jpg 18w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Acc\u00e8s et badges d'entreprise<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c261ed5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c261ed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/elementor\/thumbs\/d9e90f8b528f03898484f86b00d4e638598ada25-5617x3745-1-scaled-rpb9s0gxh5l1mcw79t7d9or9cxu2fg7jpouuwq08u8.jpg\" title=\"Surveillance continue du glucose\" alt=\"Continuous glucose monitoring\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Surveillance continue du glucose<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84cd298 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"84cd298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/elementor\/thumbs\/39897375-rpb9rr2jkt86e99usp53kr4nf34eah68cec03ye6kg.jpg\" title=\"39897375\" alt=\"39897375\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Suivi intelligent des animaux de compagnie et des actifs<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c49d73 e-flex e-con-boxed e-con e-parent\" data-id=\"9c49d73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b02133 elementor-widget elementor-widget-heading\" data-id=\"3b02133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explorez nos technologies d'automatisation pour la maison et le bureau<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df45148 elementor-widget elementor-widget-text-editor\" data-id=\"df45148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"11,1,1,0\">RJY propose une gamme de modules informatiques standard pour la domotique et de kits d'affichage parfaitement adapt\u00e9s aux sc\u00e9narios HMI de bureau. Tous les modules prennent en charge une personnalisation compl\u00e8te et garantissent une compatibilit\u00e9 transparente avec les principales architectures de marques d'automatisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fcbd82 elementor-widget elementor-widget-heading\" data-id=\"8fcbd82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Modules d'affichage<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8fc986 e-con-full e-flex e-con e-child\" data-id=\"d8fc986\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9f5bdce e-con-full e-flex e-con e-child\" data-id=\"9f5bdce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-891b387 elementor-widget elementor-widget-image\" data-id=\"891b387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.3-inch-lcd-touch-display.jpg\" class=\"elementor-animation-float attachment-large size-large wp-image-42389\" alt=\"\" srcset=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.3-inch-lcd-touch-display.jpg 800w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.3-inch-lcd-touch-display-300x300.jpg 300w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.3-inch-lcd-touch-display-500x500.jpg 500w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.3-inch-lcd-touch-display-150x150.jpg 150w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.3-inch-lcd-touch-display-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ff26e6 e-con-full e-flex e-con e-child\" data-id=\"9ff26e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e03fdf6 elementor-widget elementor-widget-heading\" data-id=\"e03fdf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">RV013Z1P<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efd12a2 elementor-widget elementor-widget-text-editor\" data-id=\"efd12a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<blockquote data-path-to-node=\"3\"><p>Le RV013Z1P-300-26 est con\u00e7u pour les appareils portables intelligents ultra-compacts et les dispositifs IoT portables, avec une technologie premium d'angle de vision complet (ALL O\u2019clock) et une interface MIPI haute vitesse soutenue par le pilote IC ST7785M stable.<\/p><p>Ce module d'affichage combine un format carr\u00e9 pr\u00e9cis de 240\u00d7240, des couleurs vives en 16,7 millions et une int\u00e9gration tactile capacitive. Fonctionnant de mani\u00e8re fiable de -20\u00b0C \u00e0 +70\u00b0C, il est parfait pour les bagues intelligentes, les mini-trackers de sant\u00e9 et les contr\u00f4leurs domestiques intelligents.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4648239 elementor-align-center elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"4648239\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rjydisplay.com\/product\/1-3-inch-square-tft-lcd-display\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cecac37 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cecac37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b01316e e-con-full e-flex e-con e-child\" data-id=\"b01316e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-934b299 e-con-full e-flex e-con e-child\" data-id=\"934b299\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78dc9ce elementor-widget elementor-widget-image\" data-id=\"78dc9ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.69-inch-lcd-display-1.jpg\" class=\"elementor-animation-float attachment-large size-large wp-image-42015\" alt=\"\" srcset=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.69-inch-lcd-display-1.jpg 800w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.69-inch-lcd-display-1-300x300.jpg 300w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.69-inch-lcd-display-1-500x500.jpg 500w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.69-inch-lcd-display-1-150x150.jpg 150w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/1.69-inch-lcd-display-1-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2322338 e-con-full e-flex e-con e-child\" data-id=\"2322338\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acf6837 elementor-widget elementor-widget-heading\" data-id=\"acf6837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">RV017YJM<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5733f3b elementor-widget elementor-widget-text-editor\" data-id=\"5733f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<blockquote data-path-to-node=\"3\"><p>Le RV017FHD est con\u00e7u pour les appareils portables intelligents compacts et les dispositifs IoT portables \u00e0 haute efficacit\u00e9, avec une technologie IPS premium grand angle de vision (Normalement Noir) et une interface SPI \u00e0 faible consommation pilot\u00e9e par le circuit int\u00e9gr\u00e9 ST7789V2 stable.<\/p><p>Ce module d'affichage combine un format rectangulaire clair de 240\u00d7280, de vraies couleurs en 16,7 millions et une plage de temp\u00e9rature industrielle \u00e9tendue (-20\u00b0C \u00e0 +70\u00b0C). Il s'int\u00e8gre parfaitement dans les trackers de sant\u00e9, les montres connect\u00e9es et les thermostats domestiques intelligents.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-137e99d elementor-align-center elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"137e99d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rjydisplay.com\/product\/1-69-inch-tft-lcd-display\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7ebc27 e-flex e-con-boxed e-con e-parent\" data-id=\"b7ebc27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38d20f2 elementor-widget elementor-widget-heading\" data-id=\"38d20f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personnalisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-914ffcd elementor-widget elementor-widget-text-editor\" data-id=\"914ffcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En tirant parti de notre conception interne et de nos solides capacit\u00e9s d'approvisionnement, RJY peut personnaliser vos besoins en affichage et en informatique embarqu\u00e9e pour qu'ils s'adaptent pr\u00e9cis\u00e9ment \u00e0 votre environnement op\u00e9rationnel et \u00e0 votre application sp\u00e9cifiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7e93e9 e-con-full e-flex e-con e-child\" data-id=\"a7e93e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79f40eb elementor-widget elementor-widget-image\" data-id=\"79f40eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213-1024x410.jpg\" class=\"attachment-large size-large wp-image-44244\" alt=\"LCD display solution - RJY Display\" srcset=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213-1024x410.jpg 1024w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213-300x120.jpg 300w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213-768x307.jpg 768w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213-18x7.jpg 18w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213-1000x400.jpg 1000w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/lcd-display-solution-1-e1765351559213.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f284da e-con-full e-flex e-con e-child\" data-id=\"9f284da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cdecb93 elementor-widget elementor-widget-heading\" data-id=\"cdecb93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les options de personnalisation d'affichage incluent :<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a2241 elementor-widget elementor-widget-text-editor\" data-id=\"46a2241\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"8,0\">Nous proposons un collage optique complet, une d\u00e9coupe personnalis\u00e9e de verre de protection circulaire\/courbe, et des traitements de surface sp\u00e9cialis\u00e9s incluant des rev\u00eatements anti-empreintes (AF). Nos contr\u00f4leurs tactiles capacitifs sont sp\u00e9cialement r\u00e9gl\u00e9s pour prendre en charge une navigation fluide sous l'eau, en cas de transpiration abondante ou avec des gants de sport \u00e9pais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-711ab9e elementor-widget elementor-widget-spacer\" data-id=\"711ab9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d4dd06 e-con-full e-flex e-con e-child\" data-id=\"6d4dd06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c83ae16 elementor-widget elementor-widget-image\" data-id=\"c83ae16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"890\" height=\"520\" src=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/PCB-Layout-Design.webp\" class=\"attachment-large size-large wp-image-40854\" alt=\"PCB Modifications - RJY Display\" srcset=\"https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/PCB-Layout-Design.webp 890w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/PCB-Layout-Design-300x175.webp 300w, https:\/\/rjydisplay.com\/wp-content\/uploads\/2025\/03\/PCB-Layout-Design-768x449.webp 768w\" sizes=\"(max-width: 890px) 100vw, 890px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e25d7f e-con-full e-flex e-con e-child\" data-id=\"5e25d7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75ae70b elementor-widget elementor-widget-heading\" data-id=\"75ae70b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><b data-path-to-node=\"11,1,1,0\" data-index-in-node=\"0\">Modifications mat\u00e9rielles embarqu\u00e9es et de PCB :<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa33dea elementor-widget elementor-widget-text-editor\" data-id=\"aa33dea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Notre \u00e9quipe d'ing\u00e9nierie interne fournit des optimisations \u00e9tendues de l'espace des circuits imprim\u00e9s cl\u00e9s en main pour les bo\u00eetiers d'appareils portables compacts. Nous prenons en charge le routage mat\u00e9riel personnalis\u00e9 pour les antennes Bluetooth BLE, le r\u00e9glage de la veille \u00e0 tr\u00e8s faible consommation, l'int\u00e9gration de capteurs biom\u00e9triques sp\u00e9cialis\u00e9s et l'approvisionnement prolong\u00e9 en composants pour les terminaux portables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"featured_media":45596,"parent":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","class_list":["post-15775","industry","type-industry","status-publish","format-standard","has-post-thumbnail","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/industry\/15775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/industry"}],"about":[{"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/types\/industry"}],"version-history":[{"count":10,"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/industry\/15775\/revisions"}],"predecessor-version":[{"id":45603,"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/industry\/15775\/revisions\/45603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/media\/45596"}],"wp:attachment":[{"href":"https:\/\/rjydisplay.com\/fr\/wp-json\/wp\/v2\/media?parent=15775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}